{"id":14323,"date":"2025-12-11T10:42:34","date_gmt":"2025-12-11T10:42:34","guid":{"rendered":"https:\/\/c5-staging.1000headsdev.com\/work\/leroy-merlin\/"},"modified":"2026-01-16T17:32:29","modified_gmt":"2026-01-16T17:32:29","slug":"leroy-merlin","status":"publish","type":"case-study","link":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/","title":{"rendered":"Leroy Merlin"},"content":{"rendered":"<div class=\"wp-block-paragraph\">\n<p>Leroy Merlin, France\u2019s leading home improvement retailer with 144 stores and 30 million monthly website visits, recognized that customers often engage online before purchasing in-store. Partnering with <strong>Cosmo5 Group company<\/strong> Arcane, Leroy Merlin aimed to create a seamless omnichannel experience that linked digital engagement with physical sales, driving significant revenue growth across both channels.<\/p>\n<\/div>\n\n\n<section  class=\"two-column-text \">\n\t\t\t<div class=\"container two-column-text__wrapper\">\n\t\t\t<div class=\"two-column-text__head\">\n\t\t\t\t<h2 class=\"two-column-text__title h4\">\n\t\t\t\t\tThe Challenge\t\t\t\t<\/h2>\n\t\t\t<\/div>\n\t\t\t<div class=\"two-column-text__main\">\n\t\t\t\t<p>Leroy Merlin sought to connect online and offline sales data, moving beyond digital-only KPIs to a holistic approach that aligned with customer shopping habits across channels. The challenge was to centralize data, automate media operations, and integrate AI-powered campaigns to enhance efficiency and effectiveness while accurately measuring omnichannel impact.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\n\n<section  class=\"two-column-text \">\n\t\t\t<div class=\"container two-column-text__wrapper\">\n\t\t\t<div class=\"two-column-text__head\">\n\t\t\t\t<h2 class=\"two-column-text__title h4\">\n\t\t\t\t\tOur Approach\t\t\t\t<\/h2>\n\t\t\t<\/div>\n\t\t\t<div class=\"two-column-text__main\">\n\t\t\t\t<p dir=\"ltr\" data-pm-slice=\"1 1 []\">We developed a comprehensive strategy to integrate Leroy Merlin\u2019s online and offline channels, leveraging data and AI to optimize performance:<\/p>\n<ul class=\"tight\" dir=\"ltr\" data-tight=\"true\">\n<li>\n<p dir=\"ltr\"><strong>Data Integration<\/strong>: Integrated in-store sales data into digital product segmentation, providing a unified view of customer behavior across all touchpoints to enable better-targeted campaigns based on real shopping patterns.<\/p>\n<\/li>\n<li>\n<p dir=\"ltr\"><strong>Redefining KPIs<\/strong>: Collaborated with Leroy Merlin to redefine KPIs for Google\u2019s Performance Max campaigns, shifting from web-only metrics to a combined omnichannel return on ad spend (ROAS) to reflect the full impact of campaigns on both online and in-store sales.<\/p>\n<\/li>\n<li>\n<p dir=\"ltr\"><strong>Real-Time Reporting &amp; AI Optimization<\/strong>: Implemented real-time reporting tools to track online and in-store sales performance, paired with AI-powered optimizations to continuously improve campaign effectiveness based on actionable insights.<\/p>\n<\/li>\n<\/ul>\n<p dir=\"ltr\">This approach ensured a seamless omnichannel experience aligned with customer behavior and business goals.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\n\n<section  class=\"photo-gallery-block\">\n\n\t<div class=\"container-fluid photo-gallery-block__wrapper\">\n\t\t\n\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"cover-img mb-3 photo-gallery-block__card\" style=\"background-image:url('https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_1-1024x683.webp');\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_1-1024x683.webp\" class=\"d-block d-md-none img-fluid\" alt=\"\" srcset=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_1-1024x683.webp 1024w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_1-300x200.webp 300w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_1-768x512.webp 768w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_1.webp 1799w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"cover-img mb-3 photo-gallery-block__card\" style=\"background-image:url('https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_2-1024x512.webp');\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_2-1024x512.webp\" class=\"d-block d-md-none img-fluid\" alt=\"\" srcset=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_2-1024x512.webp 1024w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_2-300x150.webp 300w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_2-768x384.webp 768w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_2.webp 1625w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"cover-img mb-3 photo-gallery-block__card\" style=\"background-image:url('https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_3-1024x512.webp');\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_3-1024x512.webp\" class=\"d-block d-md-none img-fluid\" alt=\"\" srcset=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_3-1024x512.webp 1024w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_3-300x150.webp 300w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_3-768x384.webp 768w, https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/leroymerlin_3.webp 1625w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/section>\n\n\n<section  class=\"two-column-text \">\n\t\t\t<div class=\"container two-column-text__wrapper\">\n\t\t\t<div class=\"two-column-text__head\">\n\t\t\t\t<h2 class=\"two-column-text__title h4\">\n\t\t\t\t\tThe Impact\t\t\t\t<\/h2>\n\t\t\t<\/div>\n\t\t\t<div class=\"two-column-text__main\">\n\t\t\t\t<p>Our strategy delivered significant growth for Leroy Merlin, supercharging digital acquisition and omnichannel marketing. The seamless integration of online and offline channels drove substantial revenue increases, enhanced campaign efficiency, and established a scalable model for sustained omnichannel success.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\n\n<section  class=\"statistics \">\n\t\t\t<div class=\"container statistics__wrapper\">\n\t\t\t<ul class=\"statistics__list\">\n\t\t\t\t\t\t\t\t\t<div class=\"statistics__item\">\n\t\t\t\t\t\t<div class=\"statistics__item__value h2\">\n\t\t\t\t\t\t\t<strong>+19%<\/strong>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"statistics__item__description\">\n\t\t\t\t\t\t\t<p>incremental <strong>web and store revenue<\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"statistics__item\">\n\t\t\t\t\t\t<div class=\"statistics__item__value h2\">\n\t\t\t\t\t\t\t<strong>+20%<\/strong>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"statistics__item__description\">\n\t\t\t\t\t\t\t<p>increase in <strong>omnichannel ROAS<\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"statistics__item\">\n\t\t\t\t\t\t<div class=\"statistics__item__value h2\">\n\t\t\t\t\t\t\t<strong>+15%<\/strong>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"statistics__item__description\">\n\t\t\t\t\t\t\t<p>increase in <strong>web ROAS<\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/section>\n\n\n<section \t\t class=\"logo-carousel module--logocarousel case-study\"\n\t\t data-module=\"carousel-logo-case-study\">\n\n\t<div class='logo-carousel__wrapper'>\n\n\t\t\t\t\t<h2 class=\"logo-carousel__title container-fluid\">\n\t\t\t\tOur <strong>Work<\/strong>\t\t\t<\/h2>\n\t\t\n\t\t<div class=\"logo-carousel__main\">\n\n\t\t\t<h2 class=\"visually-hidden\">Our Featured Case Studies<\/h2>\n\n\t\t\t\t\t\t\t\n<div class=\"logo-carousel__viewport view_1\">\n\t<div class=\"logo-carousel__bg\" aria-hidden=\"true\"><\/div>\n\t<div class=\"logo-carousel__slider js-logo-carousel__slider swiper\" role=\"region\" aria-label=\"Featured case study carousel\">\n\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14327\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Clarins\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/clarins\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14327-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/08.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_clarins-300x150.webp\" alt=\"Clarins logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14327-title\">\n\t\t\t\t\tClarins\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+170% increase in usage<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tBrand &amp; Creative Strategy\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Revolutionized Clarins\u2019 Digital Engagement with Unified Data and A\/B Testing\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14334\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Colnago\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/colnago\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14334-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/07.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_colnago-300x150.webp\" alt=\"Colnago logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14334-title\">\n\t\t\t\t\tColnago\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+33% CTR<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tIntegrated Media Strategy &amp; Planning\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Positioned Colnago at the Crossroads of Sport and Fashion\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14335\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"De\u2019 Longhi\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/de-longhi\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14335-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/08.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_delonghi-300x150.webp\" alt=\"De\u2019 Longhi logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14335-title\">\n\t\t\t\t\tDe\u2019 Longhi\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+9% e-commerce sales margin<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tDashboards &amp; Data Visualisation\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Transformed De\u2019Longhi\u2019s Advertising Strategy to Drive Profit-Centered Growth\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14352\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Diageo\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/diageo\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14352-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/Gradient-28.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_diageo-300x150.webp\" alt=\"Diageo logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14352-title\">\n\t\t\t\t\tDiageo\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">x3 AMEC Awards<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tSocial Transformation\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow we used Social Transformation\u2122 Elevating Diageo&#8217;s Social Presence Across Iconic Brands\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14312\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Ghd\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/ghd\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14312-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/01.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_ghd-300x150.webp\" alt=\"Ghd logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14312-title\">\n\t\t\t\t\tGhd\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+27% ROAS on PPC<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tCommerce\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Elevated GHD\u2019s Christmas Collection and Performance Through Strategic Collaboration\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14311\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Haier\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/haier\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14311-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/08.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_haier-300x150.webp\" alt=\"Haier logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14311-title\">\n\t\t\t\t\tHaier\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+213% YoY ad sales<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tAudience Intelligence &amp; Planning\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Drove Haier Europe\u2019s Holiday Season Success with a Dynamic Amazon Ads Strategy\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14314\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Hisense\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/hisense\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14314-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/03.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_hisense-300x150.webp\" alt=\"Hisense logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14314-title\">\n\t\t\t\t\tHisense\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+510% purchase rate<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tProduct Feed &amp; Performance Management\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Amplified Hisense\u2019s Reach and Sales Through Full-Funnel Strategy During EURO2024\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14325\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"KIABI\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/kiabi\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14325-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/06.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_kiabi-300x150.webp\" alt=\"KIABI logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14325-title\">\n\t\t\t\t\tKIABI\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+259% increase in video views<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tSocial Commerce &amp; Emerging Channels\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Transformed KIABI\u2019s YouTube Strategy into an Omnichannel Growth Engine\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14316\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"L\u2019Or\u00e9al\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/l-oreal\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14316-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/05.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_loreal-300x150.webp\" alt=\"L\u2019Or\u00e9al logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14316-title\">\n\t\t\t\t\tL\u2019Or\u00e9al\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">-20% in cost per click<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tProprietary Technology Solutions\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Amplified L\u2019Or\u00e9al Canada\u2019s Youth To The People Growth with a Sustainability-First Strategy\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-14323\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Leroy Merlin\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-14323-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/04.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_leroy-merlin-300x150.webp\" alt=\"Leroy Merlin logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-14323-title\">\n\t\t\t\t\tLeroy Merlin\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">20% increase in omnichannel<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tProduct Feed &amp; Performance Management\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Enhanced Leroy Merlin\u2019s Omnichannel Success with Seamless Online-Offline Integration\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"logo-carousel__navigation\" role=\"group\" aria-label=\"Carousel Navigation\">\n\t\t<div class=\"swiper-button-prev logo-carousel__nav-btn logo-carousel__nav-btn-prev js-logo-carousel__nav-btn-prev cosmo-nav-btn cosmo-nav-btn-prev\" aria-label=\"Previous slide\"><i class=\"fa-regular fa-chevron-left\"><\/i><\/div>\n\t\t\n\t\t<div class=\"swiper-pagination logo-carousel__pagination js-logo-carousel__pagination cosmo-pagination\" role=\"tablist\"><\/div>\n\n\t\t<div class=\"swiper-button-next logo-carousel__nav-btn logo-carousel__nav-btn-next js-logo-carousel__nav-btn-next cosmo-nav-btn cosmo-nav-btn-next\" aria-label=\"Next slide\"><i class=\"fa-regular fa-chevron-right\"><\/i><\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\n\t<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Leroy Merlin, France\u2019s leading home improvement retailer with 144 stores and 30 million monthly website visits, recognized that customers often engage online before purchasing in-store. Partnering with Cosmo5 Group company Arcane, Leroy Merlin aimed to create a seamless omnichannel experience that linked digital engagement with physical sales, driving significant revenue growth across both channels.<\/p>\n","protected":false},"featured_media":14324,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":true},"cap_category":[],"content-scope":[614],"class_list":["post-14323","case-study","type-case-study","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leroy Merlin Case Study | Cosmo5<\/title>\n<meta name=\"description\" content=\"Discover how Cosmo5 designed an omnichannel strategy for Leroy Merlin, integrating data, media and automation to drive both ROAS and revenue.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leroy Merlin Case Study | Cosmo5\" \/>\n<meta property=\"og:description\" content=\"Discover how Cosmo5 designed an omnichannel strategy for Leroy Merlin, integrating data, media and automation to drive both ROAS and revenue.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/\" \/>\n<meta property=\"og:site_name\" content=\"Cosmo5\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T17:32:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/Gradient-22.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/work\\\/leroy-merlin\\\/\",\"url\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/work\\\/leroy-merlin\\\/\",\"name\":\"Leroy Merlin Case Study | Cosmo5\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/work\\\/leroy-merlin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/work\\\/leroy-merlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/images-cdn.cosmo5.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gradient-22.webp\",\"datePublished\":\"2025-12-11T10:42:34+00:00\",\"dateModified\":\"2026-01-16T17:32:29+00:00\",\"description\":\"Discover how Cosmo5 designed an omnichannel strategy for Leroy Merlin, integrating data, media and automation to drive both ROAS and revenue.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/work\\\/leroy-merlin\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/work\\\/leroy-merlin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/work\\\/leroy-merlin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/images-cdn.cosmo5.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gradient-22.webp\",\"contentUrl\":\"https:\\\/\\\/images-cdn.cosmo5.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gradient-22.webp\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/work\\\/leroy-merlin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leroy Merlin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/#website\",\"url\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/\",\"name\":\"Cosmo5\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/#organization\",\"name\":\"Cosmo5\",\"url\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/images-cdn.cosmo5.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c5_logo.svg\",\"contentUrl\":\"https:\\\/\\\/images-cdn.cosmo5.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c5_logo.svg\",\"caption\":\"Cosmo5\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leroy Merlin Case Study | Cosmo5","description":"Discover how Cosmo5 designed an omnichannel strategy for Leroy Merlin, integrating data, media and automation to drive both ROAS and revenue.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/","og_locale":"en_US","og_type":"article","og_title":"Leroy Merlin Case Study | Cosmo5","og_description":"Discover how Cosmo5 designed an omnichannel strategy for Leroy Merlin, integrating data, media and automation to drive both ROAS and revenue.","og_url":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/","og_site_name":"Cosmo5","article_modified_time":"2026-01-16T17:32:29+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/Gradient-22.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/","url":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/","name":"Leroy Merlin Case Study | Cosmo5","isPartOf":{"@id":"https:\/\/cosmo5.com\/en-ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/#primaryimage"},"image":{"@id":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/#primaryimage"},"thumbnailUrl":"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/Gradient-22.webp","datePublished":"2025-12-11T10:42:34+00:00","dateModified":"2026-01-16T17:32:29+00:00","description":"Discover how Cosmo5 designed an omnichannel strategy for Leroy Merlin, integrating data, media and automation to drive both ROAS and revenue.","breadcrumb":{"@id":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/#primaryimage","url":"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/Gradient-22.webp","contentUrl":"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/Gradient-22.webp","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/cosmo5.com\/en-ca\/work\/leroy-merlin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cosmo5.com\/en-ca\/"},{"@type":"ListItem","position":2,"name":"Leroy Merlin"}]},{"@type":"WebSite","@id":"https:\/\/cosmo5.com\/en-ca\/#website","url":"https:\/\/cosmo5.com\/en-ca\/","name":"Cosmo5","description":"","publisher":{"@id":"https:\/\/cosmo5.com\/en-ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmo5.com\/en-ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/cosmo5.com\/en-ca\/#organization","name":"Cosmo5","url":"https:\/\/cosmo5.com\/en-ca\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/cosmo5.com\/en-ca\/#\/schema\/logo\/image\/","url":"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/c5_logo.svg","contentUrl":"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/c5_logo.svg","caption":"Cosmo5"},"image":{"@id":"https:\/\/cosmo5.com\/en-ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cosmo5.com\/en-ca\/wp-json\/wp\/v2\/case-study\/14323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmo5.com\/en-ca\/wp-json\/wp\/v2\/case-study"}],"about":[{"href":"https:\/\/cosmo5.com\/en-ca\/wp-json\/wp\/v2\/types\/case-study"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cosmo5.com\/en-ca\/wp-json\/wp\/v2\/media\/14324"}],"wp:attachment":[{"href":"https:\/\/cosmo5.com\/en-ca\/wp-json\/wp\/v2\/media?parent=14323"}],"wp:term":[{"taxonomy":"cap_category","embeddable":true,"href":"https:\/\/cosmo5.com\/en-ca\/wp-json\/wp\/v2\/cap_category?post=14323"},{"taxonomy":"content-scope","embeddable":true,"href":"https:\/\/cosmo5.com\/en-ca\/wp-json\/wp\/v2\/content-scope?post=14323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}