{"id":8583,"date":"2025-12-05T12:20:39","date_gmt":"2025-12-05T12:20:39","guid":{"rendered":"https:\/\/c5-staging.1000headsdev.com\/core-capabilities\/"},"modified":"2025-12-31T03:49:00","modified_gmt":"2025-12-31T03:49:00","slug":"core-capabilities","status":"publish","type":"page","link":"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/","title":{"rendered":"Services"},"content":{"rendered":"\n<section  class=\"page-hero-banner hero-banner-mode hero-with-toc\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"blob five\"><\/div>\n\t\t<div class=\"hero-banner-container no-gradient\">\n\t\t\t<div class=\"hero-banner-content\">\n\t\t\t\t<div class=\"banner-main-content\">\n\t\t\t\t\t<div class=\"banner-left\">\n\t\t\t\t\t\t<nav class=\"banner-breadcrumb\"><span><span><a href=\"https:\/\/cosmo5.com\/en-sg\/\">Home<\/a><\/span><\/span><\/nav>\t\t\t\t\t\t\t\t\t\t\t\t\t<h1 id=\"page-title\" class=\"banner-headline\">\n\t\t\t\t\t\t\t\tOur Universe<br \/>\r\nof <strong>Expertise<\/strong>\t\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-description\">\n\t\t\t\t\t\t\t\t<p>Our Universe of Expertise brings together the five core capabilities that power Cosmo5: Media, Commerce, Creative, Data and Technology.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"banner-right\">\n\t\t\t\t\t\t\t<nav class=\"banner-toc has-scroll-content\"\n\t\t\t\t\t\t\t     aria-label=\"Contents\" data-sticky-enabled=\"true\">\n\t\t\t\t\t\t\t\t<div class=\"toc-title\">Contents<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"toc-list\" role=\"menu\"><\/ul>\n\t\t\t\t\t\t\t\t<div class=\"toc-scroll-indicator visible pointing-down\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"hero-observer-sentinel\" aria-hidden=\"true\"><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section\n\tid=\"block_236686a29d5b409942b99314cdb3db19\"\tclass=\"services-block module\"\n\trole=\"region\"\n\taria-labelledby=\"block_236686a29d5b409942b99314cdb3db19-title\"\n>\n\t<div class=\"container-fluid services-block__wrapper\">\n\n\t\t<h2 id=\"block_236686a29d5b409942b99314cdb3db19-title\" class=\"visually-hidden\">\n\t\t\tCore Capabilities\t\t<\/h2>\n\n\t\t<ul class=\"services-block__list container\" role=\"list\">\n\n\t\t\t\n\t\t\t\t<li class=\"services-block__item\" role=\"none\" id=\"media\" data-nav-label=\"Media\">\n\t\t\t\t\t<article\n\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-0\"\n\t\t\t\t\t\tclass=\"service-card\"\n\t\t\t\t\t\trole=\"listitem\"\n\t\t\t\t\t\taria-labelledby=\"block_236686a29d5b409942b99314cdb3db19-card-0-title\"\n\t\t\t\t\t\taria-describedby=\"block_236686a29d5b409942b99314cdb3db19-card-0-body\"\n\t\t\t\t\t\t style=\"background-image:url(https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/Gradient-7.webp);\"\t\t\t\t\t>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-mob\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/media-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"service-card__wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-0-title\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__title\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<strong>Media<\/strong>\n\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-0-body\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__body\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\tWe deliver integrated media strategies tailored to each business objective, combining earned and paid media, across the full customer journey. Our end-to-end approach merges media planning, audience targeting, platform expertise, and local market knowledge to drive lasting, measurable results.\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"service-card__points\" role=\"list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Branding &#038; Experience Activation<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Community Management &#038; Organic Engagement<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Influencer Marketing &#038; Brand Advocacy<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Integrated Media Strategy &#038; Planning<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Performance Marketing Channels<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class='service-card__media'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-desk\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/media-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__slider js-service-card__slider swiper\" role=\"region\" aria-label=\"Featured case study carousel\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__navigation\" role=\"group\" aria-label=\"Carousel Navigation\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-prev service-card__nav-btn service-card__nav-btn-prev js-service-card__nav-btn-prev cosmo-nav-btn cosmo-nav-btn-prev\" aria-label=\"Previous slide\"><span class='dashicons dashicons-arrow-left-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination service-card__pagination js-service-card__pagination cosmo-pagination\" role=\"tablist\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-next service-card__nav-btn service-card__nav-btn-next js-service-card__nav-btn-next cosmo-nav-btn cosmo-nav-btn-next\" aria-label=\"Next slide\"><span class='dashicons dashicons-arrow-right-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\n\t\t\t\n\t\t\t\t<li class=\"services-block__item\" role=\"none\" id=\"commerce\" data-nav-label=\"Commerce\">\n\t\t\t\t\t<article\n\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-1\"\n\t\t\t\t\t\tclass=\"service-card\"\n\t\t\t\t\t\trole=\"listitem\"\n\t\t\t\t\t\taria-labelledby=\"block_236686a29d5b409942b99314cdb3db19-card-1-title\"\n\t\t\t\t\t\taria-describedby=\"block_236686a29d5b409942b99314cdb3db19-card-1-body\"\n\t\t\t\t\t\t style=\"background-image:url(https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/Gradient-10.webp);\"\t\t\t\t\t>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-mob\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/commerce-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"service-card__wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-1-title\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__title\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<strong>Commerce<\/strong>\n\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-1-body\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__body\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\tWe craft commerce strategies that convert. With a 360\u00b0 perspective on how people discover and buy, we build, optimize, and activate connected sales ecosystems that drive growth across eCommerce sites, retail platforms like Amazon, partner channels, social commerce, and physical points of sale.\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"service-card__points\" role=\"list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Social Commerce &#038; Emerging Channels<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Product Feed &#038; Performance Management<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Marketplace Optimization &#038; Retail Media Solutions<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>DTC &#038; Owned Channel Enablement<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Commerce Strategy &#038; Transformation<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class='service-card__media'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-desk\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/commerce-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__slider js-service-card__slider swiper\" role=\"region\" aria-label=\"Featured case study carousel\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__navigation\" role=\"group\" aria-label=\"Carousel Navigation\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-prev service-card__nav-btn service-card__nav-btn-prev js-service-card__nav-btn-prev cosmo-nav-btn cosmo-nav-btn-prev\" aria-label=\"Previous slide\"><span class='dashicons dashicons-arrow-left-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination service-card__pagination js-service-card__pagination cosmo-pagination\" role=\"tablist\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-next service-card__nav-btn service-card__nav-btn-next js-service-card__nav-btn-next cosmo-nav-btn cosmo-nav-btn-next\" aria-label=\"Next slide\"><span class='dashicons dashicons-arrow-right-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\n\t\t\t\n\t\t\t\t<li class=\"services-block__item\" role=\"none\" id=\"creative\" data-nav-label=\"Creative\">\n\t\t\t\t\t<article\n\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-2\"\n\t\t\t\t\t\tclass=\"service-card\"\n\t\t\t\t\t\trole=\"listitem\"\n\t\t\t\t\t\taria-labelledby=\"block_236686a29d5b409942b99314cdb3db19-card-2-title\"\n\t\t\t\t\t\taria-describedby=\"block_236686a29d5b409942b99314cdb3db19-card-2-body\"\n\t\t\t\t\t\t style=\"background-image:url(https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/Gradient-28.webp);\"\t\t\t\t\t>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-mob\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/creative-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"service-card__wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-2-title\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__title\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<strong>Creative<\/strong>\n\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-2-body\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__body\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\tWe are passionate about producing creative work that rewards attention and helps brands find their place in culture. Our capabilities encompass the full creative and brand building spectrum from brand strategy, through integrated campaign planning, to go-to-market activation.\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"service-card__points\" role=\"list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Integrated Campaign Development<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Production &#038; Generative AI<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Omni-Channel Content Creation<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Brand &#038; Creative Strategy<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Visual Identity &#038; Design Systems<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class='service-card__media'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-desk\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/creative-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__slider js-service-card__slider swiper\" role=\"region\" aria-label=\"Featured case study carousel\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__navigation\" role=\"group\" aria-label=\"Carousel Navigation\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-prev service-card__nav-btn service-card__nav-btn-prev js-service-card__nav-btn-prev cosmo-nav-btn cosmo-nav-btn-prev\" aria-label=\"Previous slide\"><span class='dashicons dashicons-arrow-left-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination service-card__pagination js-service-card__pagination cosmo-pagination\" role=\"tablist\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-next service-card__nav-btn service-card__nav-btn-next js-service-card__nav-btn-next cosmo-nav-btn cosmo-nav-btn-next\" aria-label=\"Next slide\"><span class='dashicons dashicons-arrow-right-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\n\t\t\t\n\t\t\t\t<li class=\"services-block__item\" role=\"none\" id=\"data\" data-nav-label=\"Data\">\n\t\t\t\t\t<article\n\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-3\"\n\t\t\t\t\t\tclass=\"service-card\"\n\t\t\t\t\t\trole=\"listitem\"\n\t\t\t\t\t\taria-labelledby=\"block_236686a29d5b409942b99314cdb3db19-card-3-title\"\n\t\t\t\t\t\taria-describedby=\"block_236686a29d5b409942b99314cdb3db19-card-3-body\"\n\t\t\t\t\t\t style=\"background-image:url(https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/Gradient-10.webp);\"\t\t\t\t\t>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-mob\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/data-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"service-card__wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-3-title\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__title\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<strong>Data<\/strong>\n\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-3-body\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__body\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\tWe turn data into a strategic growth driver. Our approach connects business goals with data strategy to build scalable, compliant ecosystems that power personalization, performance, and smarter decisions across the full marketing lifecycle.\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"service-card__points\" role=\"list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Performance Measurement &#038; Optimisation<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Data Strategy &#038; Governance<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Dashboards &#038; Data Visualisation<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Audience Intelligence &#038; Planning<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Advanced Analytics &#038; AI Modelling<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class='service-card__media'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-desk\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/data-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__slider js-service-card__slider swiper\" role=\"region\" aria-label=\"Featured case study carousel\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__navigation\" role=\"group\" aria-label=\"Carousel Navigation\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-prev service-card__nav-btn service-card__nav-btn-prev js-service-card__nav-btn-prev cosmo-nav-btn cosmo-nav-btn-prev\" aria-label=\"Previous slide\"><span class='dashicons dashicons-arrow-left-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination service-card__pagination js-service-card__pagination cosmo-pagination\" role=\"tablist\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-next service-card__nav-btn service-card__nav-btn-next js-service-card__nav-btn-next cosmo-nav-btn cosmo-nav-btn-next\" aria-label=\"Next slide\"><span class='dashicons dashicons-arrow-right-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\n\t\t\t\n\t\t\t\t<li class=\"services-block__item\" role=\"none\" id=\"technology\" data-nav-label=\"Technology\">\n\t\t\t\t\t<article\n\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-4\"\n\t\t\t\t\t\tclass=\"service-card\"\n\t\t\t\t\t\trole=\"listitem\"\n\t\t\t\t\t\taria-labelledby=\"block_236686a29d5b409942b99314cdb3db19-card-4-title\"\n\t\t\t\t\t\taria-describedby=\"block_236686a29d5b409942b99314cdb3db19-card-4-body\"\n\t\t\t\t\t\t style=\"background-image:url(https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/Gradient-30.webp);\"\t\t\t\t\t>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-mob\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/technology-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"service-card__wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-4-title\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__title\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<strong>Technology<\/strong>\n\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\n\t\t\t\t\t\t\t\t\tid=\"block_236686a29d5b409942b99314cdb3db19-card-4-body\"\n\t\t\t\t\t\t\t\t\tclass=\"service-card__body\"\n\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\tWe help brands navigate and pioneer the tech landscape &#8211; identifying the right stack, securing it, and scaling it through trusted partnerships and in-house expertise. From tech advisory to AI deployment and proprietary solutions, we deliver secure, scalable platforms built for impact.\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"service-card__points\" role=\"list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Technology Strategy &#038; Architecture<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Strategic Certified Tech Partnerships<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Proprietary Technology Solutions<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Platform &#038; Product Engineering<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>AI Engineering &#038; Intelligent Systems<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class='service-card__media'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"service-card__icon-wrap m-desk\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/technology-1.gif\" class=\"service-card__icon\" alt=\"\" aria-hidden=\"true\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__slider js-service-card__slider swiper\" role=\"region\" aria-label=\"Featured case study carousel\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"service-card__navigation\" role=\"group\" aria-label=\"Carousel Navigation\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-prev service-card__nav-btn service-card__nav-btn-prev js-service-card__nav-btn-prev cosmo-nav-btn cosmo-nav-btn-prev\" aria-label=\"Previous slide\"><span class='dashicons dashicons-arrow-left-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination service-card__pagination js-service-card__pagination cosmo-pagination\" role=\"tablist\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-next service-card__nav-btn service-card__nav-btn-next js-service-card__nav-btn-next cosmo-nav-btn cosmo-nav-btn-next\" aria-label=\"Next slide\"><span class='dashicons dashicons-arrow-right-alt'><\/span><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\n\t\t\t\n\t\t<\/ul>\n\n\t<\/div>\n<\/section>\n\n<!-- ld+json generated by: render.php -->\n<script type=\"application\/ld+json\">\n{\n    \"@context\": \"https:\/\/schema.org\",\n    \"dateModified\": \"2026-07-15T00:28:03+00:00\",\n    \"@type\": \"ItemList\",\n    \"name\": \"Services\",\n    \"description\": \"\",\n    \"numberOfItems\": 5,\n    \"itemListElement\": [\n        {\n            \"@type\": \"ListItem\",\n            \"position\": 1,\n            \"item\": {\n                \"@type\": \"Service\",\n                \"name\": \"Media\",\n                \"provider\": {\n                    \"@type\": \"Organization\",\n                    \"name\": \"Cosmo5\"\n                },\n                \"serviceType\": \"Services\"\n            }\n        },\n        {\n            \"@type\": \"ListItem\",\n            \"position\": 2,\n            \"item\": {\n                \"@type\": \"Service\",\n                \"name\": \"Commerce\",\n                \"provider\": {\n                    \"@type\": \"Organization\",\n                    \"name\": \"Cosmo5\"\n                },\n                \"serviceType\": \"Services\"\n            }\n        },\n        {\n            \"@type\": \"ListItem\",\n            \"position\": 3,\n            \"item\": {\n                \"@type\": \"Service\",\n                \"name\": \"Creative\",\n                \"provider\": {\n                    \"@type\": \"Organization\",\n                    \"name\": \"Cosmo5\"\n                },\n                \"serviceType\": \"Services\"\n            }\n        },\n        {\n            \"@type\": \"ListItem\",\n            \"position\": 4,\n            \"item\": {\n                \"@type\": \"Service\",\n                \"name\": \"Data\",\n                \"provider\": {\n                    \"@type\": \"Organization\",\n                    \"name\": \"Cosmo5\"\n                },\n                \"serviceType\": \"Services\"\n            }\n        },\n        {\n            \"@type\": \"ListItem\",\n            \"position\": 5,\n            \"item\": {\n                \"@type\": \"Service\",\n                \"name\": \"Technology\",\n                \"provider\": {\n                    \"@type\": \"Organization\",\n                    \"name\": \"Cosmo5\"\n                },\n                \"serviceType\": \"Services\"\n            }\n        }\n    ]\n}\n<\/script>\n\n\n<section \t\t class=\"logo-carousel module--logocarousel case-study\"\n\t\t data-module=\"carousel-logo-case-study\">\n\n\t<div class='logo-carousel__wrapper'>\n\n\t\t\t\t\t<h2 class=\"logo-carousel__title container-fluid\">\n\t\t\t\tOur <strong>Work<\/strong>\t\t\t<\/h2>\n\t\t\n\t\t<div class=\"logo-carousel__main\">\n\n\t\t\t<h2 class=\"visually-hidden\">Our Featured Case Studies<\/h2>\n\n\t\t\t\t\t\t\t\n<div class=\"logo-carousel__viewport view_1\">\n\t<div class=\"logo-carousel__bg\" aria-hidden=\"true\"><\/div>\n\t<div class=\"logo-carousel__slider js-logo-carousel__slider swiper\" role=\"region\" aria-label=\"Featured case study carousel\">\n\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15347\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Clarins\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/clarins\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15347-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/04.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_clarins-300x150.webp\" alt=\"Clarins logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15347-title\">\n\t\t\t\t\tClarins\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+170% increase in usage<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tBrand &amp; Creative Strategy\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Revolutionized Clarins\u2019 Digital Engagement with Unified Data and A\/B Testing\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15350\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Colnago\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/colnago\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15350-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/07.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_colnago-300x150.webp\" alt=\"Colnago logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15350-title\">\n\t\t\t\t\tColnago\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+33% CTR<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tIntegrated Media Strategy &amp; Planning\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Positioned Colnago at the Crossroads of Sport and Fashion\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15380\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"De\u2019 Longhi\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/de-longhi\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15380-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/05.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_delonghi-300x150.webp\" alt=\"De\u2019 Longhi logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15380-title\">\n\t\t\t\t\tDe\u2019 Longhi\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+9% e-commerce sales margin<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tDashboards &amp; Data Visualisation\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Transformed De\u2019Longhi\u2019s Advertising Strategy to Drive Profit-Centered Growth\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15395\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Diageo\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/diageo\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15395-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/Gradient-28.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_diageo-300x150.webp\" alt=\"Diageo logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15395-title\">\n\t\t\t\t\tDiageo\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">x3 AMEC Awards<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow we used Social Transformation\u2122 Elevating Diageo&#8217;s Social Presence Across Iconic Brands\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15356\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Ghd\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/ghd\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15356-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/05.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_ghd-300x150.webp\" alt=\"Ghd logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15356-title\">\n\t\t\t\t\tGhd\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+27% ROAS on PPC<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tCommerce\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Elevated GHD\u2019s Christmas Collection and Performance Through Strategic Collaboration\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15353\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Haier\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/haier\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15353-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/02.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_haier-300x150.webp\" alt=\"Haier logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15353-title\">\n\t\t\t\t\tHaier\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+213% YoY ad sales<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tAudience Intelligence &amp; Planning\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Drove Haier Europe\u2019s Holiday Season Success with a Dynamic Amazon Ads Strategy\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15359\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Hisense\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/hisense\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15359-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/08.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_hisense-300x150.webp\" alt=\"Hisense logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15359-title\">\n\t\t\t\t\tHisense\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+510% purchase rate<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tProduct Feed &amp; Performance Management\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Amplified Hisense\u2019s Reach and Sales Through Full-Funnel Strategy During EURO2024\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15374\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"KIABI\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/kiabi\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15374-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/07.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_kiabi-300x150.webp\" alt=\"KIABI logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15374-title\">\n\t\t\t\t\tKIABI\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">+259% increase in video views<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tSocial Commerce &amp; Emerging Channels\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Transformed KIABI\u2019s YouTube Strategy into an Omnichannel Growth Engine\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15362\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"L\u2019Or\u00e9al\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/l-oreal\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15362-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/03.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_loreal-300x150.webp\" alt=\"L\u2019Or\u00e9al logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15362-title\">\n\t\t\t\t\tL\u2019Or\u00e9al\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">-20% in cost per click<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tProprietary Technology Solutions\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Amplified L\u2019Or\u00e9al Canada\u2019s Youth To The People Growth with a Sustainability-First Strategy\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"logo-carousel__slide swiper-slide\" id=\"carousel-casestudy-slide-15371\">\n\t\t\t\t\t\n<article class=\"post-card\" data-client=\"Leroy Merlin\">\n\t<a class='post-card__wrapper' href=\"https:\/\/cosmo5.com\/en-sg\/work\/leroy-merlin\/\"\n\t   aria-labelledby=\"carousel-casestudy-slide-15371-title\">\n\t\t<img decoding=\"async\" class=\"post-card__bg\" src=\"https:\/\/cosmo5.com\/wp-content\/themes\/cosmo5evo\/assets\/src\/gradients\/04.webp\"\n\t\t     alt=\"Background visual\" aria-hidden=\"true\" loading=\"lazy\" \/>\n\t\t\t\t\t<img decoding=\"async\" class=\"post-card__logo\" src=\"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/client_leroy-merlin-300x150.webp\" alt=\"Leroy Merlin logo\" loading=\"lazy\" \/>\n\t\t\t\t<div class=\"post-card__meta\">\n\t\t\t<div class=\"post-card__head\">\n\t\t\t\t<div class=\"post-card__client\"\n\t\t\t\t     id=\"carousel-casestudy-slide-15371-title\">\n\t\t\t\t\tLeroy Merlin\t\t\t\t<\/div>\n\t\t\t\t<div class=\"post-card__result\">20% increase in omnichannel<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"post-card__bottom\">\n\t\t\t\t<div class='post-card__bottom__wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-card__service\">\n\t\t\t\t\t\t\t\tProduct Feed &amp; Performance Management\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"post-card__teaser text-small\">\n\t\t\t\t\t\t\tHow We Enhanced Leroy Merlin\u2019s Omnichannel Success with Seamless Online-Offline Integration\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='post-card__arrow'>\n\t\t\t\t\t<span class='post-card__arrow__icon dashicons dashicons-arrow-right-alt'><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"logo-carousel__navigation\" role=\"group\" aria-label=\"Carousel Navigation\">\n\t\t<div class=\"swiper-button-prev logo-carousel__nav-btn logo-carousel__nav-btn-prev js-logo-carousel__nav-btn-prev cosmo-nav-btn cosmo-nav-btn-prev\" aria-label=\"Previous slide\"><i class=\"fa-regular fa-chevron-left\"><\/i><\/div>\n\t\t\n\t\t<div class=\"swiper-pagination logo-carousel__pagination js-logo-carousel__pagination cosmo-pagination\" role=\"tablist\"><\/div>\n\n\t\t<div class=\"swiper-button-next logo-carousel__nav-btn logo-carousel__nav-btn-next js-logo-carousel__nav-btn-next cosmo-nav-btn cosmo-nav-btn-next\" aria-label=\"Next slide\"><i class=\"fa-regular fa-chevron-right\"><\/i><\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\n\t<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":32,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8583","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Services | Media, Commerce, Creative, Data &amp; Tech<\/title>\n<meta name=\"description\" content=\"Discover the Cosmo5 service universe, from media and commerce to creative, data and technology, and explore how our teams support your marketing challenges.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Services | Media, Commerce, Creative, Data &amp; Tech\" \/>\n<meta property=\"og:description\" content=\"Discover the Cosmo5 service universe, from media and commerce to creative, data and technology, and explore how our teams support your marketing challenges.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/\" \/>\n<meta property=\"og:site_name\" content=\"Cosmo5\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-31T03:49:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/core-capabilities\\\/\",\"url\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/core-capabilities\\\/\",\"name\":\"Services | Media, Commerce, Creative, Data & Tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/#website\"},\"datePublished\":\"2025-12-05T12:20:39+00:00\",\"dateModified\":\"2025-12-31T03:49:00+00:00\",\"description\":\"Discover the Cosmo5 service universe, from media and commerce to creative, data and technology, and explore how our teams support your marketing challenges.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/core-capabilities\\\/#breadcrumb\"},\"inLanguage\":\"en-SG\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/core-capabilities\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/core-capabilities\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/#website\",\"url\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/\",\"name\":\"Cosmo5\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-SG\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/#organization\",\"name\":\"Cosmo5\",\"url\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-SG\",\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/images-cdn.cosmo5.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c5_logo.svg\",\"contentUrl\":\"https:\\\/\\\/images-cdn.cosmo5.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c5_logo.svg\",\"caption\":\"Cosmo5\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmo5.com\\\/en-sg\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Services | Media, Commerce, Creative, Data & Tech","description":"Discover the Cosmo5 service universe, from media and commerce to creative, data and technology, and explore how our teams support your marketing challenges.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/","og_locale":"en_US","og_type":"article","og_title":"Services | Media, Commerce, Creative, Data & Tech","og_description":"Discover the Cosmo5 service universe, from media and commerce to creative, data and technology, and explore how our teams support your marketing challenges.","og_url":"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/","og_site_name":"Cosmo5","article_modified_time":"2025-12-31T03:49:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/","url":"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/","name":"Services | Media, Commerce, Creative, Data & Tech","isPartOf":{"@id":"https:\/\/cosmo5.com\/en-sg\/#website"},"datePublished":"2025-12-05T12:20:39+00:00","dateModified":"2025-12-31T03:49:00+00:00","description":"Discover the Cosmo5 service universe, from media and commerce to creative, data and technology, and explore how our teams support your marketing challenges.","breadcrumb":{"@id":"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/#breadcrumb"},"inLanguage":"en-SG","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cosmo5.com\/en-sg\/core-capabilities\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cosmo5.com\/en-sg\/core-capabilities\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cosmo5.com\/en-sg\/"},{"@type":"ListItem","position":2,"name":"Services"}]},{"@type":"WebSite","@id":"https:\/\/cosmo5.com\/en-sg\/#website","url":"https:\/\/cosmo5.com\/en-sg\/","name":"Cosmo5","description":"","publisher":{"@id":"https:\/\/cosmo5.com\/en-sg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmo5.com\/en-sg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-SG"},{"@type":"Organization","@id":"https:\/\/cosmo5.com\/en-sg\/#organization","name":"Cosmo5","url":"https:\/\/cosmo5.com\/en-sg\/","logo":{"@type":"ImageObject","inLanguage":"en-SG","@id":"https:\/\/cosmo5.com\/en-sg\/#\/schema\/logo\/image\/","url":"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/c5_logo.svg","contentUrl":"https:\/\/images-cdn.cosmo5.com\/wp-content\/uploads\/2025\/12\/c5_logo.svg","caption":"Cosmo5"},"image":{"@id":"https:\/\/cosmo5.com\/en-sg\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cosmo5.com\/en-sg\/wp-json\/wp\/v2\/pages\/8583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmo5.com\/en-sg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cosmo5.com\/en-sg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cosmo5.com\/en-sg\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/cosmo5.com\/en-sg\/wp-json\/wp\/v2\/comments?post=8583"}],"version-history":[{"count":0,"href":"https:\/\/cosmo5.com\/en-sg\/wp-json\/wp\/v2\/pages\/8583\/revisions"}],"wp:attachment":[{"href":"https:\/\/cosmo5.com\/en-sg\/wp-json\/wp\/v2\/media?parent=8583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}